{"id":14136,"date":"2024-09-12T09:42:13","date_gmt":"2024-09-12T07:42:13","guid":{"rendered":"https:\/\/www.museum-re.de\/?p=14136"},"modified":"2024-09-12T13:05:26","modified_gmt":"2024-09-12T11:05:26","slug":"hans-hartungs-kuenstlerisches-vorgehen-spontan-oder-kalkuliert","status":"publish","type":"post","link":"https:\/\/www.museum-re.de\/de\/museum\/aktuelles\/hans-hartungs-kuenstlerisches-vorgehen-spontan-oder-kalkuliert\/","title":{"rendered":"Hans Hartungs k\u00fcnstlerisches Vorgehen \u2013 spontan oder kalkuliert?"},"content":{"rendered":"<div class=\"ce ce-onecol      \">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col\">\n\t\t\t\t<p>Am 21. September 2024 j\u00e4hrt sich Hans Hartungs Geburtstag zum 120. Mal. Bereits in seiner Kindheit zeigte sich eine Neigung, die seine sp\u00e4tere k\u00fcnstlerische Ausdrucksform ma\u00dfgeblich pr\u00e4gen sollte. Als Grundsch\u00fcler begann Hans Hartung (1904-1989), abstrakte Bilder in Hefte zu malen, um seine Angst vor Blitzen zu bew\u00e4ltigen: \u201eIch wollte ihr Zickzack nachzeichnen noch bevor es donnerte \u2013 dadurch bannte ich den Blitz\u201c (1). Diese fr\u00fche Auseinandersetzung mit der Fl\u00fcchtigkeit des Moments beeinflusste seine Gestik: \u201eSie gaben mir ein Gef\u00fchl f\u00fcr die Schnelligkeit des Strichs und die Lust, mit dem Stift oder dem Pinsel den Augenblick einzufangen. Sie haben mich das Dr\u00e4ngende der Spontanit\u00e4t gelehrt (1).\u201c<\/p>\n<p>Besch\u00e4ftigt man sich mit Hartungs \u0152uvre, st\u00f6\u00dft man h\u00e4ufig auf die schnell gesetzten Liniaturen, die auf den ersten Blick einen Eindruck von Spontanit\u00e4t vermitteln. Doch Hartungs eigene Beschreibung des vermeintlich einfachen, senkrechten Strichs offenbart eine subtile kalkulierte Herangehensweise im Malprozess: \u201eMan muss sich vorstellen, die Leinwand ist sehr gro\u00df. Und es muss in einem einzigen Zug gelingen. [&#8230;] Man braucht ein genaues Gesp\u00fcr f\u00fcr die Richtung. Dann kommt der Moment, in dem nichts schiefgehen darf [&#8230;]. Entweder man verpatzt es oder es gelingt (2)\u201c, erkl\u00e4rte Hartung.<\/p>\n<p>Bis in die zweite H\u00e4lfte der 1950er-Jahre folgte Hartung w\u00e4hrend seines Schaffens einem bestimmten Ablauf: Er fertigte zun\u00e4chst eine kleine Tuschezeichnung an, die sp\u00e4ter als Grundlage f\u00fcr ein \u00d6lgem\u00e4lde diente. Hier zeigt sich die kalkulierte Seite seiner Kunst. Sp\u00e4ter begann er mit Industriefarben direkt auf der Leinwand zu arbeiten.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"ce ce-onecol      \">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col\">\n\t\t\t\t<figure><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7109\" src=\"https:\/\/www.museum-re.de\/wp-content\/uploads\/2024\/02\/B_091-2.png\" alt=\"\" width=\"1500\" height=\"935\" srcset=\"https:\/\/www.museum-re.de\/wp-content\/uploads\/2024\/02\/B_091-2.png 1500w, https:\/\/www.museum-re.de\/wp-content\/uploads\/2024\/02\/B_091-2-800x499.png 800w, https:\/\/www.museum-re.de\/wp-content\/uploads\/2024\/02\/B_091-2-1024x638.png 1024w, https:\/\/www.museum-re.de\/wp-content\/uploads\/2024\/02\/B_091-2-768x479.png 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n<p>Hans Hartung, <em>T 1971-H15<\/em>, 1971 \u00a9Courtesy of Tajan<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"ce ce-onecol      \">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col\">\n\t\t\t\t<p>Ein exemplarisches Werk aus dieser Phase ist <em>T 1971-H15<\/em>, welches sich in der Sammlung Reinhard Ernst befindet: Drei Schw\u00fcnge in Gelb, Schwarz und Blau treffen sich in der oberen rechten Bildecke, \u00fcberlagern einander und bilden eine kuppelartige Form. Auf ihrem Weg zum unteren Rand der Leinwand f\u00e4chern sie sich breit aus. Die gestischen Pinselstriche wirken kraftvoll und z\u00fcgig ausgef\u00fchrt, zugleich entschlossen und kontrolliert gesetzt \u2013 keine Spritzer, keine laufende Farbe.<\/p>\n<p>Mit Gewissheit k\u00f6nnen wir sagen, dass Hans Hartung es geschafft hatte, das Spontane und Kalkulierte in seinen Werken zu vereinen. W\u00e4hrend die Schnelligkeit und Direktheit seiner gestischen Malerei auf eine impulsive Herangehensweise hindeuten, zeugen Pr\u00e4zision und \u00dcberlegung, mit der er seine Werke schuf, von einer Auseinandersetzung mit Form und Technik. Beide Elemente \u2013 das Spontane und das Kalkulierte \u2013 pr\u00e4gen so die au\u00dfergew\u00f6hnliche Bildsprache des K\u00fcnstlers.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t<div class=\"ce ce-accordion      \">\n\t\t  <div class=\"container\">\n\t\t\t<div class=\"row\">\n\t\t\t  <div class=\"col\">\n\t\t\t\t<div class=\"accordion\"><div class=\"accordion-panel\" data-panel-id=\"quellen\">\n\t<div class=\"accordion-headline\">\n\t\t<h4>Quellen<\/h4>\n\t<\/div>\n\t<div class=\"accordion-content\">\n\t\t<div class=\"accordion-content-inner\">\n\n\n<div class=\"ce ce-onecol      \">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col\">\n\t\t\t\t<p>(1) ARTE (2019): Hans Hartung &#8211; Malen so schnell wie der Blitz, Min. 01:53-02:10.<\/p>\n<p>(2) ARTE (2019): Hans Hartung &#8211; Malen so schnell wie der Blitz, Min. 39:42-40:29.<\/p>\n<p>Foto: Monti, Paolo. [Hans Hartung alla Galleria Lorenzelli]. N.p., 1959.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Innerhalb der Schaffensprozesse der abstrakten Kunst nach 1945 spielt die impulsive Geste von K\u00fcnstler:innen eine zentrale Rolle. Doch ist es ebenso m\u00f6glich, die scheinbaren Widerspr\u00fcche von Spontanit\u00e4t und Kalkulation in einem abstrakten Werk zu vereinen? In diesem Beitrag erfahren Sie mehr \u00fcber den einzigartigen Schaffensprozess des deutsch-franz\u00f6sischen Malers Hans Hartung (1904\u20131989).<\/p>\n","protected":false},"author":8,"featured_media":14160,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"10019,6349,10695,12844,6433,9972","_relevanssi_noindex_reason":"","footnotes":""},"categories":[23],"tags":[790,789],"class_list":["post-14136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kunst","tag-abstrakte-kunst","tag-hartung"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/posts\/14136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/comments?post=14136"}],"version-history":[{"count":9,"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/posts\/14136\/revisions"}],"predecessor-version":[{"id":14345,"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/posts\/14136\/revisions\/14345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/media\/14160"}],"wp:attachment":[{"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/media?parent=14136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/categories?post=14136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.museum-re.de\/de\/wp-json\/wp\/v2\/tags?post=14136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}